{"id":45454,"date":"2023-04-21T19:24:21","date_gmt":"2023-04-21T19:24:21","guid":{"rendered":"https:\/\/smartyplantsnursery.com\/product\/clusia-de-hoja-pequena-clusia-guttifera\/"},"modified":"2026-03-09T11:27:55","modified_gmt":"2026-03-09T11:27:55","slug":"clusia-de-hoja-pequena-clusia-guttifera","status":"publish","type":"product","link":"https:\/\/smartyplantsnursery.com\/es\/product\/clusia-de-hoja-pequena-clusia-guttifera\/","title":{"rendered":"Clusia de hoja peque\u00f1a &#8211; clusia guttifera"},"content":{"rendered":"<p><b>Usos generales en el paisaje:<\/b> setos de privacidad o cortavientos, plantaciones de amortiguaci\u00f3n costera, plantaciones en contenedores o macizos de flores elevados, arbustos de arte topiario<\/p>\n<p><b>Notas sobre la restauraci\u00f3n ecol\u00f3gica:<\/b> No recomendado<\/p>\n<p><b>Descripci\u00f3n:<\/b> La clusia de hoja peque\u00f1a, tambi\u00e9n conocida como manzana de paso, se puede utilizar como seto o como planta de pantalla. Son tolerantes a la sal y a la sequ\u00eda y f\u00e1ciles de mantener. Las hojas son gruesas y atractivas y ofrecen un aspecto tropical para cualquier paisaje.  <\/p>\n<p><b>Dimensiones:<\/b> Altura 25 pies; Extensi\u00f3n 4 &#8211; 10 pies.<\/p>\n<p><b>Tasa de crecimiento:<\/b> De moderada a r\u00e1pida<\/p>\n<p><b>Distribuci\u00f3n nativa:<\/b> Caribe y partes de Am\u00e9rica Central<\/p>\n<p><b>H\u00e1bitats nativos:<\/b> Bosques costeros, hamacas tropicales, matorrales y afloramientos rocosos de piedra caliza<\/p>\n<p><b>Suelos:<\/b> Bien drenados, arenosos o rocosos<\/p>\n<p><b>Requisitos nutricionales:<\/b> De bajos a moderados<\/p>\n<p><b>Tolerancia al agua salada:<\/b> alta<\/p>\n<p><b>Tolerancia al viento salado:<\/b> alta<\/p>\n<p><b>Tolerancia a la sequ\u00eda:<\/b> de seco a moderado<\/p>\n<p><b>Requisitos de luz:<\/b> pleno sol a sol parcial<\/p>\n<p><b>Color de la flor:<\/b> Blanco rosado<\/p>\n<p><b>Caracter\u00edsticas de la flor:<\/b> Peque\u00f1a, cerosa, en forma de estrella<\/p>\n<p><b>Temporada de floraci\u00f3n:<\/b> Verano<\/p>\n<p><b>Fruto:<\/b> C\u00e1psulas verdes que se vuelven marrones<\/p>\n<p><b>Vida silvestre y ecolog\u00eda:<\/b> Las aves pueden comer la fruta, el denso follaje proporciona cobertura para la anidaci\u00f3n<\/p>\n<p><b>Notas de horticultura:<\/b> Cultivado a partir de esquejes, semillas<\/p>\n<p><b>Comentarios:<\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-31863\" src=\"https:\/\/smartyplantsnursery.com\/wp-content\/uploads\/2023\/04\/Screen-Shot-2023-04-22-at-11.28.02-PM-300x134.png\" alt=\"\" width=\"300\" height=\"134\"><\/p>\n<div class=\"container\">\n<div class=\"table-container\">\n<table>\n<thead>\n<tr>\n<th>Tama\u00f1o de la maceta<\/th>\n<th>Altura media plantada (desde la tierra hasta la parte superior de la planta)<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>1 gal\u00f3n\/6&#8243;<\/td>\n<td>0 &#8211; 1 ft.<\/td>\n<\/tr>\n<tr>\n<td>3 galones\/10&#8243;<\/td>\n<td>1 &#8211; 2 pies<\/td>\n<\/tr>\n<tr>\n<td>7 galones\/14&#8243;<\/td>\n<td>2 &#8211; 4 pies<\/td>\n<\/tr>\n<tr>\n<td>15 galones\/17&#8243;<\/td>\n<td>4 &#8211; 6 pies<\/td>\n<\/tr>\n<tr>\n<td>25 galones\/21&#8243;<\/td>\n<td>6 &#8211; 8 pies<\/td>\n<\/tr>\n<tr>\n<td>45 galones\/28&#8243;<\/td>\n<td>8 &#8211; 10 pies<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n","protected":false},"featured_media":51317,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[340,362,376,304,359,357,310,317,384,315,302,309,313,326,316,335,322,330,332,303,307],"product_tag":[318,352],"class_list":{"0":"post-45454","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alta","7":"product_cat-alta-es-2","8":"product_cat-alta-es-3","9":"product_cat-arbusto","10":"product_cat-arena","11":"product_cat-baja-es-3","12":"product_cat-bien-drenado","13":"product_cat-contenedor","14":"product_cat-costero","15":"product_cat-esquejes","16":"product_cat-exotica","17":"product_cat-moderada","18":"product_cat-moderada-es","19":"product_cat-moderada-es-2","20":"product_cat-pequena","21":"product_cat-pleno-sol","22":"product_cat-rapido","23":"product_cat-semilla","24":"product_cat-seto","25":"product_cat-sol-parcial","26":"product_cat-verano","27":"product_tag-blanco","28":"product_tag-rosa","29":"pa_pot-size-1-galon-6","30":"pa_pot-size-15-galones-17","31":"pa_pot-size-25-galones-21","32":"pa_pot-size-3-galones-10","33":"pa_pot-size-45-galones-28","34":"pa_pot-size-7-galones-14","37":"first","38":"instock","39":"featured","40":"taxable","41":"shipping-taxable","42":"purchasable","43":"product-type-variable"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/smartyplantsnursery.com\/es\/wp-json\/wp\/v2\/product\/45454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartyplantsnursery.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/smartyplantsnursery.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/smartyplantsnursery.com\/es\/wp-json\/wp\/v2\/comments?post=45454"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smartyplantsnursery.com\/es\/wp-json\/wp\/v2\/media\/51317"}],"wp:attachment":[{"href":"https:\/\/smartyplantsnursery.com\/es\/wp-json\/wp\/v2\/media?parent=45454"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/smartyplantsnursery.com\/es\/wp-json\/wp\/v2\/product_brand?post=45454"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/smartyplantsnursery.com\/es\/wp-json\/wp\/v2\/product_cat?post=45454"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/smartyplantsnursery.com\/es\/wp-json\/wp\/v2\/product_tag?post=45454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}